{"id":56438,"date":"2022-05-15T12:12:12","date_gmt":"2022-05-15T07:42:12","guid":{"rendered":"https:\/\/rezvanmedia.com\/?p=56438"},"modified":"2022-06-22T12:13:40","modified_gmt":"2022-06-22T07:43:40","slug":"quds-day","status":"publish","type":"post","link":"https:\/\/rezvanmedia.com\/en\/2022\/05\/15\/quds-day\/","title":{"rendered":"Quds day"},"content":{"rendered":"<p><strong>Quds day<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-56438 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-1\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56319\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56319'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-2\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56320\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56320'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-3\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56321\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56321'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56322\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56322'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56323\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56323'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56324\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56324'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-7\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56325\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56325'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-8\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56326\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-8.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56326'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-9\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56327\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-9.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56327'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-10\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56328\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-10.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56328'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-11\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56329\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-11.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56329'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-12\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56330\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-12.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56330'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-13\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56331\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-13.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56331'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-14\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56332\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-14.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56332'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-15\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56333\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-15.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56333'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-16\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56334\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-16.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56334'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-17\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56335\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-17.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56335'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-18\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56336\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-18.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56336'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-19\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56337\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-19.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56337'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-20\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56338\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-20.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56338'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-21\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56339\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-21.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56339'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-22\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56340\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-22.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56340'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-23\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56341\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-23.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56341'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-24\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56342\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-24.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56342'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-25\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56343\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-25.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56343'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/rezvanmedia.com\/en\/quds-day-26\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Quds day\" aria-describedby=\"gallery-1-56344\" srcset=\"https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26-150x150.jpg 150w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26-300x300.jpg 300w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26-1024x1024.jpg 1024w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26-768x768.jpg 768w, https:\/\/rezvanmedia.com\/en\/wp-content\/uploads\/2022\/06\/Quds-day-26.jpg 1080w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-56344'>\n\t\t\t\tQuds day\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Quds day<\/p>\n","protected":false},"author":2,"featured_media":56339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[2767,2607],"tags":[2677],"class_list":["post-56438","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-gallery","category-the-zionist-regime","tag-qods-day","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/posts\/56438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/comments?post=56438"}],"version-history":[{"count":0,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/posts\/56438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/media\/56339"}],"wp:attachment":[{"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/media?parent=56438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/categories?post=56438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rezvanmedia.com\/en\/wp-json\/wp\/v2\/tags?post=56438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}